{"id":3817,"date":"2022-11-12T19:56:18","date_gmt":"2022-11-12T19:56:18","guid":{"rendered":"https:\/\/www.michaellaitman.com\/es\/?p=3817"},"modified":"2022-11-12T19:56:18","modified_gmt":"2022-11-12T19:56:18","slug":"los-iranies-estan-despertando","status":"publish","type":"post","link":"https:\/\/www.michaellaitman.com\/es\/news\/los-iranies-estan-despertando\/","title":{"rendered":"Los iran\u00edes est\u00e1n despertando"},"content":{"rendered":" Foto: Gente enciende fuego en una protesta por la muerte de Mahsa Amini, una chica que muri\u00f3 despu\u00e9s de ser arrestada por la \u00abpolic\u00eda de la moralidad\u00bb de la rep\u00fablica isl\u00e1mica, en Teher\u00e1n, Ir\u00e1n, 21\/sep\/22. WANA (West Asia News Agency) v\u00eda REUTERS\n<p><span style=\"font-weight: 400\">A pesar de los riesgos obvios para su seguridad y de d\u00e9cadas de opresi\u00f3n por parte de la ortodoxia isl\u00e1mica, los j\u00f3venes iran\u00edes dicen \u00ab\u00a1Ya es suficiente!\u00bb Las protestas comenzaron tras la muerte de Mahsa Amini, de veintid\u00f3s a\u00f1os, estando bajo custodia policial. Supuestamente, la Patrulla de Orientaci\u00f3n, la \u00abpolic\u00eda de la moralidad\u00bb isl\u00e1mica de Ir\u00e1n, <a href=\"https:\/\/www.facebook.com\/Laitmanesp\/videos\/622975116047357\/\">la golpe\u00f3<\/a> hasta dejarla inconsciente y la acus\u00f3 de violar la moda, relacionada con un \u00abhijab inadecuado\u00bb. Luego de la golpiza, entr\u00f3 en estado de coma y despu\u00e9s de varios d\u00edas falleci\u00f3. Desde que comenzaron las protestas, el 14 de septiembre, se han extendido por todo el pa\u00eds y ahora est\u00e1n dirigidas a la propia organizaci\u00f3n religiosa.<\/span><\/p>\n<p><span style=\"font-weight: 400\">A pesar del temor de volver a los escenarios de los disturbios de 2019, cuando, seg\u00fan los informes, murieron 1,500 personas y a pesar de las diecisiete muertes que ya se han informado, en enfrentamientos con la polic\u00eda y la Guardia Revolucionaria de Ir\u00e1n, los iran\u00edes no se desaniman. Han despertado y ya no est\u00e1n dispuestos a ser silenciados.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Siempre he dicho que Ir\u00e1n es un pa\u00eds muy especial. Es una naci\u00f3n antigua con una historia gloriosa, el pueblo es sabio y muy desarrollado. Aunque, en las \u00faltimas d\u00e9cadas, han sido severamente oprimidos por un r\u00e9gimen isl\u00e1mico ortodoxo, que no les permite prosperar. La tensi\u00f3n entre las cualidades del pueblo iran\u00ed y el r\u00e9gimen que los oprime, se est\u00e1 volviendo demasiado intensa para contenerla, de ah\u00ed el brote de 2019 y el actual. Espero que los cambios que se avecinan sean positivos.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Hay cambios no s\u00f3lo en Ir\u00e1n, sino en todo el mundo e Ir\u00e1n no puede aislarse. Es m\u00e1s, ahora que los iran\u00edes est\u00e1n saliendo a la calle, los acontecimientos inspirar\u00e1n a los ciudadanos de otros pa\u00edses musulmanes a hacer lo mismo. El papel de liderazgo de Ir\u00e1n en el mundo isl\u00e1mico funciona en ambos sentidos: cuando es m\u00e1s extremo, los pa\u00edses que lo siguen, tambi\u00e9n se vuelven extremos. Cuando son m\u00e1s abiertos, tambi\u00e9n lo hacen los otros.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Por eso, es dif\u00edcil que el gobierno de Ir\u00e1n acepte voluntariamente las demandas de apertura de los manifestantes. Pero, cuando soplan vientos de cambio, soplan en todo el mundo. Ning\u00fan pa\u00eds escapa.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Personalmente, doy la bienvenida a estos cambios en Ir\u00e1n. Creo que son lo mejor y s\u00e9 que a Israel, nada le gustar\u00eda m\u00e1s que restaurar las relaciones c\u00e1lidas que alguna vez tuvo con el pueblo y el gobierno iran\u00ed.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pesar de los riesgos obvios para su seguridad y de d\u00e9cadas de opresi\u00f3n por parte de la ortodoxia isl\u00e1mica, los j\u00f3venes iran\u00edes dicen \u00ab\u00a1Ya es suficiente!\u00bb Las protestas comenzaron tras la muerte de Mahsa Amini, de veintid\u00f3s a\u00f1os, estando<span class=\"ellipsis\">&hellip;<\/span><\/p>\n<div class=\"read-more\"><a href=\"https:\/\/www.michaellaitman.com\/es\/news\/los-iranies-estan-despertando\/\">Leer m\u00e1s \u203a<\/a><\/div>\n<p><!-- end of .read-more --><\/p>\n","protected":false},"author":76,"featured_media":5458,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[3],"tags":[139,290],"class_list":["post-3817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-nueva-humanidad","tag-iran"],"_links":{"self":[{"href":"https:\/\/www.michaellaitman.com\/es\/wp-json\/wp\/v2\/posts\/3817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.michaellaitman.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.michaellaitman.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.michaellaitman.com\/es\/wp-json\/wp\/v2\/users\/76"}],"replies":[{"embeddable":true,"href":"https:\/\/www.michaellaitman.com\/es\/wp-json\/wp\/v2\/comments?post=3817"}],"version-history":[{"count":0,"href":"https:\/\/www.michaellaitman.com\/es\/wp-json\/wp\/v2\/posts\/3817\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.michaellaitman.com\/es\/wp-json\/wp\/v2\/media\/5458"}],"wp:attachment":[{"href":"https:\/\/www.michaellaitman.com\/es\/wp-json\/wp\/v2\/media?parent=3817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.michaellaitman.com\/es\/wp-json\/wp\/v2\/categories?post=3817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.michaellaitman.com\/es\/wp-json\/wp\/v2\/tags?post=3817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}