{"id":2506,"date":"2023-02-21T03:41:11","date_gmt":"2023-02-21T02:41:11","guid":{"rendered":"https:\/\/www.michaellaitman.com\/de\/?p=2506"},"modified":"2026-05-08T21:30:05","modified_gmt":"2026-05-08T19:30:05","slug":"ja-man-lebt-in-einer-blase-und-das-ist-nicht-unbedingt-schlecht","status":"publish","type":"post","link":"https:\/\/www.michaellaitman.com\/de\/news\/ja-man-lebt-in-einer-blase-und-das-ist-nicht-unbedingt-schlecht\/","title":{"rendered":"Ja, man lebt in einer Blase &#8211; und das ist nicht unbedingt schlecht"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:24% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.michaellaitman.com\/de\/wp-content\/uploads\/2023\/06\/main-thumb-837693994-200-pydfvbnvwekwnphfmusdyebqzivsxznc.jpeg\" alt=\"\" class=\"wp-image-3828 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Wir alle leben in unseren eigenen Blasen, und das ist nicht unbedingt etwas Schlechtes. Unsere Blasen zeichnen sich dadurch aus, dass wir kein Verlangen nach irgendetwas au\u00dferhalb dieser Blasen haben.<\/p>\n<\/div><\/div>\n\n\n\n<p>In meinem pers\u00f6nlichen physischen Leben verlasse ich zum Beispiel kaum mein Zimmer. Dort lebe und arbeite ich. Manchmal gehe ich aus und reise, aber nur, wenn es n\u00f6tig ist, und f\u00fcr solche Gelegenheiten plane ich im Voraus. Es hat viele Vorteile, in einer solchen Blase zu leben, denn so habe ich das Gef\u00fchl, dass ich die optimalen Mittel habe, um meine Sch\u00fcler zu unterrichten und Inhalte zu schaffen, die der Menschheit dienen.<\/p>\n\n\n\n<p>Das Leben in einer physischen Blase bedeutet jedoch nicht, dass ich in einer Wahrnehmungsblase lebe, d. h. in einer Blase meiner Verbindung mit der Welt und mit anderen Menschen. Ich habe meine Kommunikationsmittel, verschiedene Arten von Medien, das Internet, das Fernsehen, das Radio, und ich habe auch ein paar Tausend Sch\u00fcler auf der ganzen Welt und Millionen von Menschen, die regelm\u00e4\u00dfig mit den Lehren in Ber\u00fchrung kommen, die ich verbreite. Ist das meine Blase? Manche w\u00fcrden sagen, ja, auch wenn es ein paar Millionen Menschen erreicht &#8211; aber es ist trotzdem eine Blase.<\/p>\n\n\n\n<p>Wir alle leben auf einem kleinen Planeten, der in einem Universum schwebt, das auch eine Blase ist. Alles ist eine Blase &#8211; auch unser Universum. Wer wei\u00df wirklich, wie viele Universen es gibt? Wir alle leben in bestimmten Blasen, und es ist nat\u00fcrlich, positiv und richtig, auf diese Weise zu leben.<\/p>\n\n\n\n<p>Unsere Wahrnehmungsblasen sind gepr\u00e4gt von unserem Charakter, unserer Natur, unserer Lebenseinstellung, unserem inneren Aufbau und der Art und Weise, wie wir die Welt wahrnehmen. Das k\u00f6nnen wir auch bei Kindern beobachten: Jedes Kind hat eine einzigartige Wahrnehmung und Herangehensweise an die Welt, gegen die wir nichts tun k\u00f6nnen.<\/p>\n\n\n\n<p>Die Tora weist uns an, die Kinder so zu erziehen, wie sie es selbst sind. Wir bauen uns also in der Tat jeder f\u00fcr sich eine bestimmte Wahrnehmung der Realit\u00e4t auf, die unsere Blase ist, und aus dieser Blase heraus, von dieser Blase aus oder in dieser Blase, beziehen wir uns auf alles im Leben. Wir k\u00f6nnen nicht sagen, ob es gut oder schlecht ist. Es ist einfach, wie wir leben.<\/p>\n\n\n\n<p>Das Gleiche gilt f\u00fcr Tiere oder f\u00fcr jeden, der sp\u00fcrt und darauf reagiert, wie die ihn umgebende Natur uns beeinflusst. Wir leben nach einem bestimmten Ansatz und einer bestimmten Einstellung, wie wir mit unseren inneren Eigenschaften auf die uns umgebende Natur reagieren, und so leben wir in einer Blase &#8211; einer Blase unserer Beziehung zur umgebenden Welt.<\/p>\n\n\n\n<p>Wir existieren in der Blase, in der wir instinktiv leben, d.h. in der uns die Natur platziert hat. Dar\u00fcber hinaus stellt sich jedoch die Frage, inwieweit wir in unserer Blase verschlossen bleiben und nicht aus ihr heraustreten wollen, und inwieweit wir uns einem Ideal oder einem Ziel widmen, das die Grenzen unserer Blase \u00fcberschreitet.<\/p>\n\n\n\n<p><em>Geschrieben\/bearbeitet von Studenten des Kabbalisten Dr. Michael Laitman.&nbsp;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir alle leben in unseren eigenen Blasen, und das ist nicht unbedingt etwas Schlechtes. Unsere Blasen zeichnen sich dadurch aus, dass wir kein Verlangen nach irgendetwas au\u00dferhalb dieser Blasen haben. In meinem pers\u00f6nlichen physischen Leben verlasse ich zum Beispiel kaum<span class=\"ellipsis\">&hellip;<\/span><\/p>\n<div class=\"read-more\"><a href=\"https:\/\/www.michaellaitman.com\/de\/news\/ja-man-lebt-in-einer-blase-und-das-ist-nicht-unbedingt-schlecht\/\">Weiterlesen \u203a<\/a><\/div>\n<p><!-- end of .read-more --><\/p>\n","protected":false},"author":86,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[19,5],"tags":[],"class_list":["post-2506","post","type-post","status-publish","format-standard","hentry","category-articles","category-news"],"_links":{"self":[{"href":"https:\/\/www.michaellaitman.com\/de\/wp-json\/wp\/v2\/posts\/2506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.michaellaitman.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.michaellaitman.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.michaellaitman.com\/de\/wp-json\/wp\/v2\/users\/86"}],"replies":[{"embeddable":true,"href":"https:\/\/www.michaellaitman.com\/de\/wp-json\/wp\/v2\/comments?post=2506"}],"version-history":[{"count":2,"href":"https:\/\/www.michaellaitman.com\/de\/wp-json\/wp\/v2\/posts\/2506\/revisions"}],"predecessor-version":[{"id":4012,"href":"https:\/\/www.michaellaitman.com\/de\/wp-json\/wp\/v2\/posts\/2506\/revisions\/4012"}],"wp:attachment":[{"href":"https:\/\/www.michaellaitman.com\/de\/wp-json\/wp\/v2\/media?parent=2506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.michaellaitman.com\/de\/wp-json\/wp\/v2\/categories?post=2506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.michaellaitman.com\/de\/wp-json\/wp\/v2\/tags?post=2506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}