{"id":1851,"date":"2022-07-21T11:01:29","date_gmt":"2022-07-21T09:01:29","guid":{"rendered":"https:\/\/www.michaellaitman.com\/de\/?p=1851"},"modified":"2026-05-12T21:36:06","modified_gmt":"2026-05-12T19:36:06","slug":"was-ist-ein-mensch","status":"publish","type":"post","link":"https:\/\/www.michaellaitman.com\/de\/news\/was-ist-ein-mensch\/","title":{"rendered":"Was ist ein Mensch?"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><strong>Der Mensch ist die h\u00f6chste von vier Ebenen in der Natur: die bewegungslose, die pflanzliche, die belebte und die menschliche.<\/strong> Tats\u00e4chlich gibt es in der Natur selbst keine Form des Menschen, es gibt nur das Bewegungslose, das Pflanzliche und das Belebte, und die menschliche Ebene entsteht, wenn wir eine besondere Art von Erziehung erfahren, die uns auf eine solche Ebene hebt.<\/p>\n\n\n\n<p>Sehen wir uns die Menschheit an, k\u00f6nnen wir dann sagen, dass sie Menschen sind, die auf der menschlichen oder auf der belebten Ebene der Natur existieren? Hier brauchen wir eine klare Definition der beiden Ebenen.<\/p>\n\n\n\n<p>Es gibt Menschen in dieser k\u00f6rperlichen Welt, die wissen, wie man sich kultiviert und zivilisiert verh\u00e4lt, d.h. auf eine Weise, die anderen nicht schadet. Vielleicht sind sie nicht einmal zur Schule gegangen, aber sie haben eine gewisse innere Intelligenz, die ihr Verhalten leitet. Im Gegensatz dazu k\u00f6nnen wir auch jemanden sehen, der an der Harvard University studiert hat, sich aber wie ein Tier verh\u00e4lt. Deshalb m\u00fcssen wir den Unterschied zwischen den beiden Ebenen, der menschlichen und der belebten, verstehen.<\/p>\n\n\n\n<p>Die Weisheit der Kabbala unterscheidet zweibeinige Lebewesen in &#8222;Mensch&#8220; und &#8222;Tier&#8220;. Ein Tier ist jemand, der das gleiche Bild wie ein Mensch hat, der aber das angeborene egoistische Verlangen nach Nahrung, Sex, Familie, Geld, Ehre, Macht und Wissen erf\u00fcllen will. Das hei\u00dft, wir k\u00f6nnten uns mit allem, was diese Welt zu bieten hat, erf\u00fcllen, mit allem Reichtum, Respekt, Ruhm, Macht, Wissen und Kunstfertigkeit, aber wir w\u00fcrden immer noch als tierisch und nicht als menschlich definiert werden, wenn unsere Absicht darin besteht, aus einem solchen Angebot an Erf\u00fcllung selbst Nutzen zu ziehen.<\/p>\n\n\n\n<p>Die menschliche Ebene bezeichnet diejenigen, die ihre Absicht von der angeborenen, auf sich selbst gerichteten Absicht auf das Wohl der anderen und der Natur ver\u00e4ndern. Im Hebr\u00e4ischen steht das Wort &#8222;Adam&#8220; f\u00fcr &#8222;Mensch&#8220;, das von dem Wort f\u00fcr &#8222;\u00e4hnlich&#8220; (&#8222;Domeh&#8220;) abgeleitet ist, von dem Satz &#8222;Domeh le Elyon&#8220; (&#8222;\u00e4hnlich dem H\u00f6chsten&#8220;). Das &#8222;H\u00f6chste&#8220; ist die h\u00f6chste Eigenschaft in der Wirklichkeit, die nat\u00fcrliche Eigenschaft der Liebe, des Gebens und der Verbindung, der kein F\u00fcnkchen Eigennutz anhaftet. So wie die Natur in ihrer grundlegenden Eigenschaft fungiert, alles innerhalb ihrer selbst zu lieben, zu beschenken, zu verbinden und zusammenzuhalten, so werden wir entsprechend einer solchen Neigung als &#8222;menschlich&#8220; bezeichnet, wenn wir uns das Erreichen der Eigenschaft der Natur zum Ziel setzen und lernen, anderen und der Natur in gleichem Ma\u00dfe zu n\u00fctzen, wie wir uns von Natur aus selbst zu n\u00fctzen w\u00fcnschen.<\/p>\n\n\n\n<p>Es ist wichtig zu verstehen, dass die Natur eine Qualit\u00e4t der Liebe ist, die wir in unseren Beziehungen zueinander erlangen k\u00f6nnen. Wenn wir die Liebe f\u00fcreinander bis zu dem Ma\u00df erreichen, wie es geschrieben steht, &#8222;liebe deinen N\u00e4chsten wie dich selbst&#8220;, dann erreichen wir einen Zustand der \u00c4hnlichkeit mit der Natur. Nach der Kabbala ist das Erreichen der \u00c4hnlichkeit mit der Eigenschaft der Liebe, des Gebens und der Verbindung mit der Natur &#8211; der Aufstieg von der belebten auf die menschliche Ebene &#8211; der h\u00f6chste Zustand, den wir in unserem Leben erreichen k\u00f6nnen; es ist der Zweck unseres Lebens, und sein Erreichen gibt uns ein Gef\u00fchl der Ewigkeit und Vollkommenheit, im Gegensatz zu allen begrenzten und unvollkommenen Empfindungen, die wir in unserem belebten Leben erleben.<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\"><em>Geschrieben\/bearbeitet von Sch\u00fclern des Kabbalisten Dr. Michael Laitman<\/em><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Der Mensch ist die h\u00f6chste von vier Ebenen in der Natur: die bewegungslose, die pflanzliche, die belebte und die menschliche. Tats\u00e4chlich gibt es in der Natur selbst keine Form des Menschen, es gibt nur das Bewegungslose, das Pflanzliche und das<span class=\"ellipsis\">&hellip;<\/span><\/p>\n<div class=\"read-more\"><a href=\"https:\/\/www.michaellaitman.com\/de\/news\/was-ist-ein-mensch\/\">Weiterlesen \u203a<\/a><\/div>\n<p><!-- end of .read-more --><\/p>\n","protected":false},"author":86,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[19,5],"tags":[],"class_list":["post-1851","post","type-post","status-publish","format-standard","hentry","category-articles","category-news"],"_links":{"self":[{"href":"https:\/\/www.michaellaitman.com\/de\/wp-json\/wp\/v2\/posts\/1851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.michaellaitman.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.michaellaitman.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.michaellaitman.com\/de\/wp-json\/wp\/v2\/users\/86"}],"replies":[{"embeddable":true,"href":"https:\/\/www.michaellaitman.com\/de\/wp-json\/wp\/v2\/comments?post=1851"}],"version-history":[{"count":1,"href":"https:\/\/www.michaellaitman.com\/de\/wp-json\/wp\/v2\/posts\/1851\/revisions"}],"predecessor-version":[{"id":4230,"href":"https:\/\/www.michaellaitman.com\/de\/wp-json\/wp\/v2\/posts\/1851\/revisions\/4230"}],"wp:attachment":[{"href":"https:\/\/www.michaellaitman.com\/de\/wp-json\/wp\/v2\/media?parent=1851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.michaellaitman.com\/de\/wp-json\/wp\/v2\/categories?post=1851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.michaellaitman.com\/de\/wp-json\/wp\/v2\/tags?post=1851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}